{"id":780,"date":"2024-12-20T14:44:10","date_gmt":"2024-12-20T14:44:10","guid":{"rendered":"https:\/\/atomausstieg.ch\/trop-dangereuses-trop-tardives-trop-cheres-les-fantaisies-nucleaires-du-conseil-federal-sont-deconnectees-de-la-realite\/"},"modified":"2024-12-20T14:51:54","modified_gmt":"2024-12-20T14:51:54","slug":"trop-dangereuses-trop-tardives-trop-cheres-les-fantaisies-nucleaires-du-conseil-federal-sont-deconnectees-de-la-realite","status":"publish","type":"post","link":"https:\/\/atomausstieg.ch\/fr\/trop-dangereuses-trop-tardives-trop-cheres-les-fantaisies-nucleaires-du-conseil-federal-sont-deconnectees-de-la-realite\/","title":{"rendered":"Trop dangereuses, trop tardives, trop ch\u00e8res &#8211; Les fantaisies nucl\u00e9aires du Conseil f\u00e9d\u00e9ral sont d\u00e9connect\u00e9es de la r\u00e9alit\u00e9"},"content":{"rendered":"\n<p>Gr\u00e2ce aux \u00e9nergies renouvelables, la Suisse pourra couvrir ses besoins \u00e9nerg\u00e9tiques \u00e0 100% avec de l&rsquo;\u00e9nergie renouvelable, indig\u00e8ne et propre. En juin dernier, le peuple suisse s&rsquo;est engag\u00e9 dans cette voie en acceptant la loi sur l&rsquo;\u00e9lectricit\u00e9. En demandant la construction de nouvelles centrales nucl\u00e9aires, le Conseil f\u00e9d\u00e9ral r\u00e9duit cette politique \u00e0 n\u00e9ant.   <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Des risques toujours aussi \u00e9lev\u00e9s<\/strong><\/h3>\n\n<p>Trop dangereuses, trop tardives, trop ch\u00e8res : telles sont les principales raisons qui plaident contre la construction de nouvelles centrales nucl\u00e9aires en Suisse. Que ce soit en Finlande, en France ou en Angleterre, la construction de r\u00e9acteurs co\u00fbte des milliards et prend beaucoup plus de temps que pr\u00e9vu. En Suisse, une nouvelle installation ne pourrait \u00eatre raccord\u00e9e au r\u00e9seau au plus t\u00f4t dans 30 ans. Une contribution du nucl\u00e9aire \u00e0 l&rsquo;objectif net z\u00e9ro 2050 de la Suisse est donc absolument irr\u00e9aliste. En revanche, le d\u00e9veloppement des \u00e9nergies renouvelables permettrait d&rsquo;augmenter la production d&rsquo;\u00e9lectricit\u00e9 beaucoup plus rapidement, de mani\u00e8re propre et fiable. De plus, une centrale nucl\u00e9aire comporte des risques bien plus \u00e9lev\u00e9s que des installations photovolta\u00efques ou \u00e9oliennes. Florian Kasser, pr\u00e9sident de l&rsquo;Alliance Sortons du nucl\u00e9aire, rappelle : \u00ab Avec les r\u00e9acteurs sur le march\u00e9, une fusion du c\u0153ur et une contamination radioactive \u00e0 grande \u00e9chelle sont toujours possibles \u00bb.<br\/>        <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Participation \u00e0 la consultation<\/strong><\/h3>\n\n<p>Le contre-projet du Conseil f\u00e9d\u00e9ral arrive seulement sept ans apr\u00e8s que le peuple suisse a d\u00e9cid\u00e9 de sortir du nucl\u00e9aire. Depuis cette d\u00e9cision, le peuple s\u2019est plusieurs fois prononc\u00e9 en faveur d&rsquo;un d\u00e9veloppement rapide des \u00e9nergies renouvelables. \u00ab Non seulement le conseiller f\u00e9d\u00e9ral R\u00f6sti ignore les d\u00e9cisions du peuple suisse, mais il cr\u00e9e \u00e9galement une incertitude dans le secteur \u00e9nerg\u00e9tique, remettant en question la politique \u00e9nerg\u00e9tique actuelle. L&rsquo;Alliance Sortons du nucl\u00e9aire appelle donc les organisations concern\u00e9e \u00e0 participer \u00e0 la consultation et \u00e0 insister sur l\u2019interdiction de nouvelles centrales nucl\u00e9aires au profit de la poursuite du d\u00e9veloppement des \u00e9nergies renouvelables.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 31 organisations de l&rsquo;Alliance \u00ab Sortons du nucl\u00e9aire \u00bb rejettent le contre-projet \u00e0 l&rsquo;Initiative pour de nouvelles centrales nucl\u00e9aires (\u201cStop au blackout\u201d) que le Conseil f\u00e9d\u00e9ral a mis aujourd&rsquo;hui en consultation. Elles l&rsquo;expliqueront dans leur r\u00e9ponse commune \u00e0 la consultation. <\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"%%post_title%%","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"footnotes":""},"categories":[30],"tags":[],"beitragstyp":[],"class_list":["post-780","post","type-post","status-publish","format-standard","hentry","category-initiative-nucleaire"],"acf":[],"_links":{"self":[{"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/posts\/780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":1,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/posts\/780\/revisions"}],"predecessor-version":[{"id":781,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/posts\/780\/revisions\/781"}],"wp:attachment":[{"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/media?parent=780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/categories?post=780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/tags?post=780"},{"taxonomy":"beitragstyp","embeddable":true,"href":"https:\/\/atomausstieg.ch\/fr\/wp-json\/wp\/v2\/beitragstyp?post=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}